{"id":5749,"date":"2023-12-20T11:00:37","date_gmt":"2023-12-20T14:00:37","guid":{"rendered":"https:\/\/sergiobertoldi.com\/?p=5749"},"modified":"2023-12-21T13:42:37","modified_gmt":"2023-12-21T16:42:37","slug":"carille-e-oficialmente-apresentado-no-santos-como-novo-treinador-para-a-temporada-de-2024","status":"publish","type":"post","link":"https:\/\/sergiobertoldi.com\/index.php\/2023\/12\/20\/carille-e-oficialmente-apresentado-no-santos-como-novo-treinador-para-a-temporada-de-2024\/","title":{"rendered":"Carille \u00e9 oficialmente apresentado no Santos como novo treinador para a temporada de 2024"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"font-family: helvetica, arial, sans-serif; font-size: 14pt;\"><strong><u>Al\u00f4 Na\u00e7\u00e3o Santista! Sauda\u00e7\u00f5es Alvinegras!<\/u><\/strong><strong><u>\u00a0<\/u><\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: tahoma, arial, helvetica, sans-serif; font-size: 14pt;\">O Santos apresentou oficialmente nesta quarta-feira (20), o t\u00e9cnico F\u00e1bio Carille, que ser\u00e1 o treinador do elenco para a temporada de 2024.<\/span><br \/>\n<span style=\"font-family: tahoma, arial, helvetica, sans-serif; font-size: 14pt;\">Desta forma o novo treinador contratado, n\u00e3o s\u00f3 \u00e9 o primeiro a encabe\u00e7ar a lista de caras novas para a pr\u00f3xima temporada, como tamb\u00e9m ser\u00e1 importante no processo de reestrutura\u00e7\u00e3o do elenco, analisando junto a Diretoria de futebol do clube, poss\u00edveis refor\u00e7os!<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: tahoma, arial, helvetica, sans-serif; font-size: 14pt;\">De volta ao Santos, nessa que ser\u00e1 a sua segunda passagem pelo clube no qual j\u00e1 havia trabalhado entre <strong>2021<\/strong> e <strong>2022<\/strong>, Carille assinou um contrato v\u00e1lido at\u00e9 o final de <strong>2024<\/strong>, com op\u00e7\u00e3o de renova\u00e7\u00e3o por mais uma temporada.<br \/>\n<\/span><span style=\"font-family: tahoma, arial, helvetica, sans-serif; font-size: 14pt;\">Ao lado do Vice Presidente do Santos, <strong>Fernando Bonavides<\/strong>, e do coordenador t\u00e9cnico, <strong>Alexandre Gallo<\/strong>, F\u00e1bio Carille concedeu entrevista coletiva na sala de imprensa da Vila Belmiro e falou sobre esse momento<\/span><\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-5752 size-full\" src=\"https:\/\/i0.wp.com\/sergiobertoldi.com\/wp-content\/uploads\/2023\/12\/Capturar.jpg?resize=644%2C419&#038;ssl=1\" alt=\"\" width=\"644\" height=\"419\" srcset=\"https:\/\/i0.wp.com\/sergiobertoldi.com\/wp-content\/uploads\/2023\/12\/Capturar.jpg?w=644&amp;ssl=1 644w, https:\/\/i0.wp.com\/sergiobertoldi.com\/wp-content\/uploads\/2023\/12\/Capturar.jpg?resize=300%2C195&amp;ssl=1 300w\" sizes=\"auto, (max-width: 644px) 100vw, 644px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: tahoma, arial, helvetica, sans-serif; font-size: 14pt;\">Carille falou sobre os motivos que o fizeram decidir pela volta ao clube, ao inv\u00e9s de cumprir seu contrato rec\u00e9m renovado com o futebol no Jap\u00e3o.<\/span><\/p>\n<blockquote>\n<p style=\"text-align: justify;\"><em><span style=\"font-family: tahoma, arial, helvetica, sans-serif; font-size: 14pt;\">Essa camisa (foi o principal motivo). Uma camisa grandiosa e hist\u00f3rica. Segundo, por ser um lugar que eu j\u00e1 trabalhei e me senti muito bem aqui. Quando sa\u00ed fiquei muito chateado. Terceiro, as conversas com Alexandre Gallo e o presidente Marcelo Teixeira foram me dando for\u00e7as e a certeza de que poderia vir aqui e fazer um bom trabalho\u201d.<\/span><\/em><\/p>\n<\/blockquote>\n<p style=\"text-align: justify;\"><span style=\"font-family: tahoma, arial, helvetica, sans-serif; font-size: 14pt;\">Carille j\u00e1 iniciou as negocia\u00e7\u00f5es com a diretoria para a montagem do elenco de 2024. O novo treinador do Peixe assegurou que formar\u00e1 um time forte para competir no Paulist\u00e3o e na S\u00e9rie B.<\/span><br \/>\n<span style=\"font-family: tahoma, arial, helvetica, sans-serif; font-size: 14pt;\">Outros tr\u00eas profissionais acompanham Carille no Peixe: o auxiliar t\u00e9cnico <strong>Leandro da Silva<\/strong>, conhecido como Cuca, o preparador f\u00edsico <strong>Cesar Mendes <\/strong>e o analista <strong>D\u00eanis Lupp<\/strong>. Todos trabalharam com Carille no futebol \u00e1rabe (<strong>Al Ittihad club<\/strong>), e no (<strong>V Varen Nagasaki<\/strong>) no futebol do Jap\u00e3o.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: tahoma, arial, helvetica, sans-serif; font-size: 14pt;\">Vale lembrar que o Santos possui um comiss\u00e3o t\u00e9cnica fixa no clube com os auxiliares <strong>Marcelo Fernandes<\/strong> e <strong>Claudiomiro<\/strong>, os preparadores f\u00edsicos <strong>Carlito Macedo<\/strong> e <strong>Emerson Polimeno<\/strong> e o preparador de goleiro <strong>Arzul<\/strong> e <strong>Juninho<\/strong>.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: tahoma, arial, helvetica, sans-serif;\"><span style=\"font-size: 14pt;\">Por fim, o novo treinador destacou as expectativas do clube para 2024, afirmando que o Santos precisa mudar sua mentalidade, deixando de pensar em evitar rebaixamentos e retomando a postura de um gigante, buscando t\u00edtulos.<\/span><strong><u>\u00a0<\/u><\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\"><strong><u>Acompanhe a Coletiva de apresenta\u00e7\u00e3o do T\u00e9cnico F\u00e1bio Carille<\/u><\/strong><\/span><\/p>\n<div class=\"jetpack-video-wrapper\"><iframe loading=\"lazy\" title=\"F\u00c1BIO CARILLE | APRESENTA\u00c7\u00c3O (20\/12\/23)\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/vLZ0Hw-ASWE?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/div>\n<p style=\"text-align: justify;\"><span style=\"font-family: tahoma, arial, helvetica, sans-serif; font-size: 14pt;\">(Cr\u00e9dito: Imagem: Raul Baretta\/Santos FC)<\/span><br \/>\n<span style=\"font-family: tahoma, arial, helvetica, sans-serif; font-size: 14pt;\">(Cr\u00e9dito: Imagem: SantosTV\/Divulga\u00e7\u00e3o\/Santos FC)<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: tahoma, arial, helvetica, sans-serif; font-size: 14pt;\">Falamos das coisas do Santos, sempre com a parceria e o apoio dos nossos anunciantes!<\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Al\u00f4 Na\u00e7\u00e3o Santista! Sauda\u00e7\u00f5es Alvinegras!\u00a0 O Santos apresentou oficialmente nesta quarta-feira (20), o t\u00e9cnico F\u00e1bio Carille, que ser\u00e1 o treinador<\/p>\n","protected":false},"author":2,"featured_media":5750,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[68,4,32],"tags":[6],"class_list":["post-5749","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-apresentacao-oficial","category-bastidores-do-santos-fc","category-treinador-santista","tag-santos-fc"],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/sergiobertoldi.com\/wp-content\/uploads\/2023\/12\/Carille-2.jpg?fit=640%2C427&ssl=1","_links":{"self":[{"href":"https:\/\/sergiobertoldi.com\/index.php\/wp-json\/wp\/v2\/posts\/5749","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergiobertoldi.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergiobertoldi.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergiobertoldi.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sergiobertoldi.com\/index.php\/wp-json\/wp\/v2\/comments?post=5749"}],"version-history":[{"count":1,"href":"https:\/\/sergiobertoldi.com\/index.php\/wp-json\/wp\/v2\/posts\/5749\/revisions"}],"predecessor-version":[{"id":5753,"href":"https:\/\/sergiobertoldi.com\/index.php\/wp-json\/wp\/v2\/posts\/5749\/revisions\/5753"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergiobertoldi.com\/index.php\/wp-json\/wp\/v2\/media\/5750"}],"wp:attachment":[{"href":"https:\/\/sergiobertoldi.com\/index.php\/wp-json\/wp\/v2\/media?parent=5749"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergiobertoldi.com\/index.php\/wp-json\/wp\/v2\/categories?post=5749"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergiobertoldi.com\/index.php\/wp-json\/wp\/v2\/tags?post=5749"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}