{"id":1470,"date":"2020-03-15T11:22:15","date_gmt":"2020-03-15T14:22:15","guid":{"rendered":"http:\/\/sergiobertoldi.com\/?p=1470"},"modified":"2020-03-15T11:22:21","modified_gmt":"2020-03-15T14:22:21","slug":"ha-quase-dois-meses-o-santos-nao-sabe-o-que-e-vencer-um-time-de-serie-a","status":"publish","type":"post","link":"https:\/\/sergiobertoldi.com\/index.php\/2020\/03\/15\/ha-quase-dois-meses-o-santos-nao-sabe-o-que-e-vencer-um-time-de-serie-a\/","title":{"rendered":"H\u00e1 quase dois meses o Santos n\u00e3o sabe o que \u00e9 vencer um time de S\u00e9rie A"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <strong><span style=\"text-decoration: underline;\">Al\u00f4 Na\u00e7\u00e3o Santista! Sauda\u00e7\u00f5es Alvinegras!<\/span><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Jogando pela 10\u00aa rodada do Campeonato Paulista, o S\u00e3o Paulo venceu na noite deste \u00faltimo S\u00e1bado, seu primeiro cl\u00e1ssico na temporada 2020.<br>O Morumbi com seus port\u00f5es fechados, totalmente vazio e sem a presen\u00e7a da torcida, teve como testemunhas de mais um San-S\u00e3o, apenas os profissionais da imprensa que foram cadastrados e autorizados para trabalhar o Cl\u00e1ssico!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tal medida restritiva, visa evitar eventos que contem com um grande contingente de pessoas, por conta da pandemia mundial do Coronav\u00edrus.<br>Mesmo sem a presen\u00e7a de sua torcida, o S\u00e3o Paulo n\u00e3o esqueceu em momento algum que jogava em sua casa, e portanto com a obriga\u00e7\u00e3o de valer seu mando, tratou de partir para cima do Santos e impor seu jogo!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O Santos por sua vez, mostrando que realmente \u00e9 hoje, uma equipe que parece n\u00e3o trazer mais nada do que havia aprendido com seu ex treinador, tentava atrair o rival e esperar o momento correto para dar o bote! \u00a0<br>E foi postado dessa maneira totalmente defensiva e correndo poucos riscos, que em um contra-ataque r\u00e1pido, o Alvinegro abriu o placar em uma triangula\u00e7\u00e3o bem feita entre os jogadores Pato Sanches, Par\u00e1, e Arthur Gomes, que finalizou a jogada fazendo aos 29 minutos da 1\u00aa etapa, Santos 1 x 0.<br>Apesar da vantagem no placar, a verdade \u00e9 que o Santos mais uma vez jogava um futebol covarde, um futebol de time pequeno, um futebol ao melhor estilo \u201cDefender e jogar por uma bola\u201d Tanto \u00e9, que at\u00e9 a feitura do gol aos 29 minutos do 1T, o Santos n\u00e3o havia dado um \u00fanico chute contra a meta s\u00e3o-paulina.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O S\u00e3o Paulo por sua vez, continuava imprimindo um ritmo forte, criando seguidas oportunidades, muitas vezes desperdi\u00e7adas por falta de precis\u00e3o no passe ou na finaliza\u00e7\u00e3o.<br>Percebendo que seu time tinha mais volume de jogo mas pecava na hora de definir a \u00faltima bola, para deixar o time com mais poder de finaliza\u00e7\u00e3o e ainda mais ofensivo, o t\u00e9cnico Fernando Diniz sacou o defensor Bruno Alves e colocou Pablo.<br>A altera\u00e7\u00e3o surtiu o efeito esperado, e o time conseguiu mudar a hist\u00f3ria da partida!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quatro personagens foram decisivos para o placar final.<br>1 &#8211; Pelo lado do Santos, o volante Jobson que infantilmente, acabou expulso ap\u00f3s uma entrada desnecess\u00e1ria no Jogador Daniel Alves, e com sua expuls\u00e3o prejudicou demais a sua equipe! <br>2 &#8211; O Goleiro Everson que falhou bisonhamente nos dois gols do S\u00e3o Paulo, e n\u00e3o inspira confian\u00e7a alguma como goleiro do Santos.<br>3 &#8211; O treinador Santista, que tamb\u00e9m falhou nas altera\u00e7\u00f5es que fez, e na demora para recompor seu sistema defensivo, ap\u00f3s a expuls\u00e3o do Jobson!<br>4 &#8211; J\u00e1 pelo lado tricolor, o personagem \u201cDecisivo\u201d, por\u00e9m positivamente para o seu time, foi o atacante Pablo que com os dois gols que fez na partida, acabou sendo  o nome do Jogo!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O curioso \u00e9 que o camisa 9, aposta do t\u00e9cnico tricolor, at\u00e9 a partida contra o Santos nesta 10\u00aa rodada, h\u00e1 nove que n\u00e3o marcava um \u00fanico gol.<br>A \u00faltima vez que o atacante Pablo havia balan\u00e7ado as redes advers\u00e1rias, foi na primeira rodada, logo na estreia do time contra o \u00c1gua Santa.<br>Desta vez, gra\u00e7as as falhas bisonhas do arqueiro Santista, e seus companheiros de defesa, Pablo precisou de apenas 21 minutos para ir \u00e0s redes duas vezes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Com a derrota no cl\u00e1ssico com o S\u00e3o Paulo, o Alvinegro Praiano permanece com os mesmos \u00a015 pontos, e agora precisar\u00e1 de uma vit\u00f3ria nos jogos finais, contra Santo Andr\u00e9 (s\u00e1bado, na Arena Barueri) ou Novorizontino, para assegurar a primeira posi\u00e7\u00e3o do Grupo A do Paulist\u00e3o.<br>Com a expuls\u00e3o, Jobson fica automaticamente suspenso para o jogo do pr\u00f3ximo s\u00e1bado contra o Santo Andr\u00e9, \u00e0s 17h (de Bras\u00edlia), em Barueri.<br>Consciente do erro que cometeu, erro que prejudicou seus companheiros e comprometeu completamente o resultado final da partida, o volante Jobson chorou muito ao deixar a partida, e em sua conta particular nas Redes Sociais, pediu desculpas \u00e0 todos!  <\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/sergiobertoldi.com\/wp-content\/uploads\/2020\/03\/WhatsApp-Image-2020-03-14-at-22.12.07-498x1024.jpeg?resize=249%2C512\" alt=\"\" class=\"wp-image-1471\" width=\"249\" height=\"512\"\/><\/figure><\/div>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/sergiobertoldi.com\/wp-content\/uploads\/2020\/03\/jobsonchora.jpg?w=800\" alt=\"\" class=\"wp-image-1472\"\/><figcaption>Inconsolado o Volante Jobson chora compulsivamente ainda nas escadas que levam aos vesti\u00e1rio do Santos<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">J\u00e1 escrevi sobre esse goleiro Everson e volto a faz\u00ea-lo: <\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/sergiobertoldi.com\/wp-content\/uploads\/2020\/03\/15597925225cf88b8ae9923_1559792522_3x2_md.jpg?resize=576%2C384\" alt=\"\" class=\"wp-image-1473\" width=\"576\" height=\"384\"\/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Eu juro que n\u00e3o me conformo, como o Santos fez esse verdadeiro absurdo de contratar um goleiro fraco como esse, e pior: Pagaram R$ 4 milh\u00f5es pelo jogador de 28 anos, porque o ex t\u00e9cnico Jorge Sampaoli, queria um atleta com qualidade nos p\u00e9s!<br>Que Qualidade? Eu n\u00e3o vejo esse goleiro, acertar um passe que seja, com os p\u00e9s!<br>Quebra todas as bolas, e quando n\u00e3o as coloca em poder dos advers\u00e1rios, em 80% das vezes coloca para fora do campo mesmo!<br>Em bolas a\u00e9reas, o cara \u00e9 um horror! <br>Ou n\u00e3o sai nas bolas, ou quando sai, sai atrasado ou catando borboletas, como no primeiro gol do S\u00e3o Paulo!<br>No segundo gol a bola ficou cruzando a pequena \u00e1rea e ele s\u00f3 olhando!<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/sergiobertoldi.com\/wp-content\/uploads\/2020\/03\/WhatsApp-Image-2020-02-17-at-10.02.45.jpeg?w=800\" alt=\"\" class=\"wp-image-1475\"\/><figcaption>Jesualdo Ferreira<\/figcaption><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Sobre o treinador, acho que quem acompanha o meu Blog j\u00e1 sabe o que penso n\u00e9?<br>Jamais me enganei ou me deixei iludir, com algumas vit\u00f3rias que andaram acontecendo, as quais eu mesmo alertei que n\u00e3o tinham rela\u00e7\u00e3o alguma com uma poss\u00edvel evolu\u00e7\u00e3o no trabalho do treinador!<br>Ali\u00e1s pergunto aos amigos: De quem o Santos ganhou at\u00e9 agora?<br><strong>Guarani, Inter de Limeira, Botafogo de Ribeir\u00e3o Preto, e Mirassol<\/strong>?<br>E ainda perdemos para o <strong>Ituano<\/strong>, e n\u00e3o fomos al\u00e9m de um empate, contra <strong>Bragantino<\/strong> e <strong>Ferrovi\u00e1ria<\/strong>. <br>Com esse senhor Jesualdo Ferreira, ainda n\u00e3o conseguimos nessa temporada, vencer nenhum time considerado de s\u00e9rie A. <br>E quando chegar no Brasileir\u00e3o, que s\u00f3 tem clubes n\u00edvel de s\u00e9rie A?<br>Continuo dizendo, que insistir na perman\u00eancia dessa Comiss\u00e3o T\u00e9cnica, \u00e9 um erro que nos custar\u00e1 caro!<br>At\u00e9 quando ir\u00e3o insistir nesse erro?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ao contr\u00e1rio do ano passado, em que foi o clube que mais venceu cl\u00e1ssicos contra o Trio de Ferro da Capital, nesse in\u00edcio de temporada 2020, o Santos termina a primeira fase do Campeonato Paulista sem vencer nenhum cl\u00e1ssico.<br>\u00a0O Peixe foi derrotado pelo <strong>Corinthians<\/strong>, pelo <strong>S\u00e3o Paulo<\/strong>, e empatou em 0 x 0 com o <strong>Palmeiras<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sem a partida que haveria na pr\u00f3xima ter\u00e7a-feira\u00a0 pela Copa Libertadores, o Santos volta \u00e0 campo no pr\u00f3ximo S\u00e1bado quando receber\u00e1 o Santo Andr\u00e9 na Arena Barueri.<br>Ainda n\u00e3o se sabe se ser\u00e1 outra partida com port\u00f5es fechados, ou se a exemplo do que j\u00e1 vem ocorrendo em outras competi\u00e7\u00f5es, o Paulist\u00e3o tamb\u00e9m ser\u00e1 interrompido por causa do Coronav\u00edrus.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><span style=\"text-decoration: underline;\">FICHA T\u00c9CNICA<\/span><br>S\u00c3O PAULO 2 X 1 SANTOS<\/strong><br>Data: <strong>14 de mar\u00e7o de 2020, s\u00e1bado<\/strong><br>Local: <strong>Est\u00e1dio do Morumbi, em S\u00e3o Paulo-SP<\/strong><br>Hor\u00e1rio: <strong>19h00 (de Bras\u00edlia)<\/strong><br>\u00c1rbitro: <strong>Luiz Flavio de Oliveira<\/strong><br>Assistentes: <strong>Daniel Paulo Ziolli e Miguel Cataneo Ribeiro da Costa<\/strong><br>Cart\u00f5es amarelos: <strong>Tch\u00ea Tch\u00ea, Arboleda e Pablo (SPFC); Jobson e Arthur Gomes (SFC)<\/strong><br>Cart\u00e3o vermelho: <strong>Jobson (SFC)<\/strong><br>P\u00fablico e renda: <strong>N\u00e3o foi permitida entrada de torcedores.<\/strong><br>GOLS: <strong>S\u00e3o Paulo: Pablo, aos 7 e aos 21 minutos do 2T<br>Santos: Arthur Gomes, aos 29 minutos do 1T.<\/strong><br>S\u00c3O PAULO: <strong>Lucas Perri; Juanfran, Bruno Alves (Pablo), Arboleda e Reinaldo; Tch\u00ea Tch\u00ea, Daniel Alves e Igor Gomes (Hernanes); Antony, Alexandre Pato e Vitor Bueno <\/strong><br>T\u00e9cnico: <strong>Fernando Diniz<\/strong><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/sergiobertoldi.com\/wp-content\/uploads\/2020\/03\/WhatsApp-Image-2020-03-14-at-18.01.20-576x1024.jpeg?resize=432%2C768\" alt=\"\" class=\"wp-image-1476\" width=\"432\" height=\"768\"\/><\/figure><\/div>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"S\u00c3O PAULO 2 X 1 SANTOS | GOL | PAULIST\u00c3O (14\/03\/20)\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/XIVKfGpKw0M?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><figcaption>Assista como foi o gol do Santos<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">N\u00e3o posso terminar a edi\u00e7\u00e3o de hoje, sem fazer um coment\u00e1rio:<br>Tudo bem que o Santos n\u00e3o jogou nenhum futebol maravilhoso, que falhas individuais foram cometidas e determinaram o resultado negativo, que temos um treinador que n\u00e3o est\u00e1 \u00e0 altura do Santos, e etc..<br>Mas que essa fam\u00edlia &#8220;Oliveira&#8221;, \u00e9 uma praga na vida do Santos, isso \u00e9!<br>Primeiro era o irm\u00e3o <strong>Paulo C\u00e9sar de Oliveira, <\/strong>que agora \u00b4virou Comentarista!<br>Agora \u00e9 o tal de &#8221; <strong>Luiz Flavio de Oliveira<\/strong>&#8221; <br>N\u00e3o adianta que com esses caras no apito, o Santos n\u00e3o ganha uma partida!<br>Oh Zica!!!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Al\u00f4 Na\u00e7\u00e3o Santista! Sauda\u00e7\u00f5es Alvinegras! Jogando pela 10\u00aa rodada do Campeonato Paulista, o S\u00e3o Paulo venceu na noite deste<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[12,25,10,16],"tags":[6],"class_list":["post-1470","post","type-post","status-publish","format-standard","hentry","category-analise-e-comentario","category-campeonato-paulista","category-elenco-profissional","category-resenha-do-jogo","tag-santos-fc"],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/sergiobertoldi.com\/index.php\/wp-json\/wp\/v2\/posts\/1470","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergiobertoldi.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergiobertoldi.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergiobertoldi.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sergiobertoldi.com\/index.php\/wp-json\/wp\/v2\/comments?post=1470"}],"version-history":[{"count":1,"href":"https:\/\/sergiobertoldi.com\/index.php\/wp-json\/wp\/v2\/posts\/1470\/revisions"}],"predecessor-version":[{"id":1478,"href":"https:\/\/sergiobertoldi.com\/index.php\/wp-json\/wp\/v2\/posts\/1470\/revisions\/1478"}],"wp:attachment":[{"href":"https:\/\/sergiobertoldi.com\/index.php\/wp-json\/wp\/v2\/media?parent=1470"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergiobertoldi.com\/index.php\/wp-json\/wp\/v2\/categories?post=1470"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergiobertoldi.com\/index.php\/wp-json\/wp\/v2\/tags?post=1470"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}